{"id":15,"count":19,"description":"Principaux produits : Protecteur d'alarme \u00e0 limitation de courant pour la protection contre les incendies, protecteur \u00e0 limitation de courant pour le comptage, protecteur \u00e0 limitation de puissance s\u00e9lective, protecteur \u00e0 limitation de charge \u00e0 limitation de courant, protecteur \u00e0 surtension et \u00e0 sous-tension \u00e0 r\u00e9armement automatique, protecteur \u00e0 surtension et \u00e0 sous-tension triphas\u00e9 \u00e0 quatre fils \u00e0 r\u00e9armement automatique, interrupteur de contr\u00f4le et de protection, voltm\u00e8tre triphas\u00e9, amp\u00e8rem\u00e8tre triphas\u00e9, amp\u00e8rem\u00e8tre programmable monophas\u00e9, compteur de puissance intelligent, protecteur de surtension, commutateur de transfert automatique (ATS).","link":"https:\/\/bright-china.com\/fr\/produit\/","name":"Produit","slug":"produit","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/bright-china.com\/fr\/wp-json\/wp\/v2\/product_cat\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bright-china.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/bright-china.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/bright-china.com\/fr\/wp-json\/wp\/v2\/product?product_cat=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}